{"id":6517,"date":"2016-11-06T20:01:21","date_gmt":"2016-11-06T19:01:21","guid":{"rendered":"https:\/\/www.dimension-3.ch\/18dim3\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/"},"modified":"2019-03-04T21:21:47","modified_gmt":"2019-03-04T20:21:47","slug":"dimension-3-gallery-training-of-pilot-students-and-paragliding-internships","status":"publish","type":"page","link":"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/","title":{"rendered":"Dimension 3 Gallery: Training of pilot students and paragliding internships"},"content":{"rendered":"            <style type=\"text\/css\">\r\n                #content-block-background-1379 { background-image: url(); background-position: center bottom; background-repeat: repeat-x; background-color: #293037; background-attachment: fixed; background-size: auto; }\r\n                #content-block-body-1379 { padding: 50px 0 50px; color: #FFFFFF; }\r\n                .content-block-body { margin-left: auto; margin-right: auto; position: relative; }\r\n            <\/style>\r\n                <style type=\"text\/css\">\r\n                    #wrapper-1 { overflow-x: hidden; }\r\n                    #content-block-background-1379 { margin: 0 -10000px; padding: 0 10000px; }\r\n                <\/style>\r\n            \r\n                \r\n            <div class=\"clear\"><\/div>\r\n            <div id=\"content-block-background-1379\" class=\"content-block-background \">\r\n                <div id=\"content-block-body-1379\" class=\"content-block-body\">\r\n                    <div class=\"clear\"><\/div>\r\n                    \n<div style=\"text-align: center;\">\n<h4 style=\"margin-bottom: 25px;\"><span style=\"font-size: 42px; color: #fff; line-height: 1.2; font-weight: bold;\">Paragliding school Dimension 3<\/span><\/h4>\n<h5 style=\"margin-bottom: 20px;\"><span style=\"font-size: 24px; color: #fff; line-height: 1.5;\">Become a pilot with the Dimension 3 paragliding school: Initiation, Progression, Performance.<\/span><\/h5>\n<\/div>\n<div class=\"one_half\"><a class=\"flat-custom-button align-btn-right\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/en\/paragliding-school\/our-courses-to-learn-paragliding-and-become-a-certified-pilot\/\" title=\"All you need to know about Dimension 3 internships\"><span style=\"padding:10px 20px; background-color:transparent; border:1px solid #FFFFFF; color:#FFFFFF; font-size:13px;\">All you need to know about Dimension 3 internships<\/span><\/a><\/div>\n<div class=\"one_half last_column\"><a class=\"flat-custom-button align-btn-left\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/en\/contact\/contact-dimension-3-for-any-information-advice-equipment-purchases\/\" title=\"Contact us\"><span style=\"padding:10px 20px; background-color:#FD7800; border:1px solid #eb6f00; color:#FFFFFF; font-size:13px;\">Contact us<\/span><\/a><\/div>\n                    <div class=\"clear\"><\/div>\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"clear\"><\/div>\r\n\n            <style type=\"text\/css\">\r\n                #content-block-background-1186 { background-image: url(); background-position: center top; background-repeat: no; background-color: #ffffff; background-attachment: scroll; background-size: auto; }\r\n                #content-block-body-1186 { padding: 40px 0 80px 0; color: #6495ED; }\r\n                .content-block-body { margin-left: auto; margin-right: auto; position: relative; }\r\n            <\/style>\r\n            \r\n                \r\n            <div class=\"clear\"><\/div>\r\n            <div id=\"content-block-background-1186\" class=\"content-block-background \">\r\n                <div id=\"content-block-body-1186\" class=\"content-block-body\">\r\n                    <div class=\"clear\"><\/div>\r\n                    \n<style type=\"text\/css\">rra.eg-henryharrison-element-1,ra.eg-henryharrison-element-2{r -webkit-transition:all .4s linear; r  -moz-transition:all .4s linear; r  -o-transition:all .4s linear; r  -ms-transition:all .4s linear; r  transition:all .4s linear; r}rrr.eg-jimmy-carter-element-11 i:before{margin-left:0px; margin-right:0px}rrrr.eg-harding-element-17{letter-spacing:1px}r.eg-harding-wrapper .esg-entry-media{overflow:hidden; r   box-sizing:border-box;r   -webkit-box-sizing:border-box;r   -moz-box-sizing:border-box;r   padding:30px 30px 0px 30px;r}rr.eg-harding-wrapper .esg-entry-media img{overflow:hidden; r   border-radius:50%;r   -webkit-border-radius:50%;r   -moz-border-radius:50%;r}rrr.eg-ulysses-s-grant-wrapper .esg-entry-media{overflow:hidden; r   box-sizing:border-box;r   -webkit-box-sizing:border-box;r   -moz-box-sizing:border-box;r   padding:30px 30px 0px 30px;r}rr.eg-ulysses-s-grant-wrapper .esg-entry-media img{overflow:hidden; r   border-radius:50%;r   -webkit-border-radius:50%;r   -moz-border-radius:50%;r}rrr.eg-richard-nixon-wrapper .esg-entry-media{overflow:hidden; r   box-sizing:border-box;r   -webkit-box-sizing:border-box;r   -moz-box-sizing:border-box;r   padding:30px 30px 0px 30px;r}rr.eg-richard-nixon-wrapper .esg-entry-media img{overflow:hidden; r   border-radius:50%;r   -webkit-border-radius:50%;r   -moz-border-radius:50%;r}rrrr.eg-herbert-hoover-wrapper .esg-entry-media img{r  filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\"); r  filter:gray; r  -webkit-filter:grayscale(100%); r}rr.eg-herbert-hoover-wrapper:hover .esg-entry-media img{r  filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");r  -webkit-filter:grayscale(0%)}rrrr.eg-lyndon-johnson-wrapper .esg-entry-media img{r  filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\"); r  filter:gray; r  -webkit-filter:grayscale(100%); r}rr.eg-lyndon-johnson-wrapper:hover .esg-entry-media img{r  filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");r  -webkit-filter:grayscale(0%)}rrrr.esg-overlay.eg-ronald-reagan-container{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); rbackground:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rfilter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}rrr.eg-georgebush-wrapper .esg-entry-cover{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); rbackground:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rfilter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}rrrrr.eg-jefferson-wrapper{-webkit-border-radius:5px !important; -moz-border-radius:5px !important; border-radius:5px !important; -webkit-mask-image:url(data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAAAEAAAABCAIAAACQd1PeAAAAGXRFWHRTb2Z0d2FyZQBBZG9iZSBJbWFnZVJlYWR5ccllPAAAAA5JREFUeNpiYGBgAAgwAAAEAAGbA+oJAAAAAElFTkSuQmCC) !important}rrr.eg-monroe-element-1{text-shadow:0px 1px 3px rgba(0,0,0,0.1)}rrr.eg-lyndon-johnson-wrapper .esg-entry-cover{background:-moz-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); rbackground:-webkit-gradient(radial,center center,0px,center center,100%,color-stop(0%,rgba(0,0,0,0.35)),color-stop(96%,rgba(18,18,18,0)),color-stop(100%,rgba(19,19,19,0))); rbackground:-webkit-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); rbackground:-o-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); rbackground:-ms-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); rbackground:radial-gradient(ellipse at center,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); rfilter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#59000000',endColorstr='#00131313',GradientType=1 ); r}rrr.eg-wilbert-wrapper .esg-entry-cover{background:-moz-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); rbackground:-webkit-gradient(radial,center center,0px,center center,100%,color-stop(0%,rgba(0,0,0,0.35)),color-stop(96%,rgba(18,18,18,0)),color-stop(100%,rgba(19,19,19,0))); rbackground:-webkit-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); rbackground:-o-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); rbackground:-ms-radial-gradient(center,ellipse cover,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); rbackground:radial-gradient(ellipse at center,rgba(0,0,0,0.35) 0%,rgba(18,18,18,0) 96%,rgba(19,19,19,0) 100%); rfilter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#59000000',endColorstr='#00131313',GradientType=1 ); r}r.eg-wilbert-wrapper .esg-entry-media img{r -webkit-transition:0.4s ease-in-out;r  -moz-transition:0.4s ease-in-out;r  -o-transition:0.4s ease-in-out;r  transition:0.4s ease-in-out;r  filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\"); r  filter:gray; r  -webkit-filter:grayscale(100%); r}rr.eg-wilbert-wrapper:hover .esg-entry-media img{r  filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");r  -webkit-filter:grayscale(0%)}rrr.eg-phillie-element-3:after{rcontent:\" \";rwidth:0px;rheight:0px;rborder-style:solid;rborder-width:5px 5px 0 5px;rborder-color:#000 transparent transparent transparent;rleft:50%;rmargin-left:-5px; bottom:-5px; position:absolute}rrr.eg-howardtaft-wrapper .esg-entry-media img,.eg-howardtaft-wrapper .esg-media-poster{r  filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='1 0 0 0 0,0 1 0 0 0,0 0 1 0 0,0 0 0 1 0'\/><\/filter><\/svg>#grayscale\");r  -webkit-filter:grayscale(0%);r}rr.eg-howardtaft-wrapper:hover .esg-entry-media img,.eg-howardtaft-wrapper:hover .esg-media-poster{r  filter:url(\"data:image\/svg+xml;utf8,<svg xmlns='http:\/\/www.w3.org\/2000\/svg'><filter id='grayscale'><feColorMatrix type='matrix' values='0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0.3333 0.3333 0.3333 0 0 0 0 0 1 0'\/><\/filter><\/svg>#grayscale\"); r  filter:gray; r  -webkit-filter:grayscale(100%); r}rrr.myportfolio-container .added_to_cart.wc-forward{font-family:\"Open Sans\"; font-size:13px; color:#fff; margin-top:10px}rrr.esgbox-title.esgbox-title-outside-wrap{font-size:15px; font-weight:700; text-align:center}r.esgbox-title.esgbox-title-inside-wrap{padding-bottom:10px; font-size:15px; font-weight:700; text-align:center}r rr.esg-content.eg-twitterstream-element-33-a{display:inline-block}r.eg-twitterstream-element-35{word-break:break-all}r.esg-overlay.eg-twitterstream-container{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); rbackground:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rfilter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}rrr.esg-content.eg-facebookstream-element-33-a{display:inline-block}r.eg-facebookstream-element-0{word-break:break-all}rrr.esg-overlay.eg-flickrstream-container{background:-moz-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:-webkit-gradient(linear,left top,left bottom,color-stop(50%,rgba(0,0,0,0)),color-stop(99%,rgba(0,0,0,0.83)),color-stop(100%,rgba(0,0,0,0.85))); rbackground:-webkit-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:-o-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:-ms-linear-gradient(top,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rbackground:linear-gradient(to bottom,rgba(0,0,0,0) 50%,rgba(0,0,0,0.83) 99%,rgba(0,0,0,0.85) 100%); rfilter:progid:DXImageTransform.Microsoft.gradient( startColorstr='#00000000',endColorstr='#d9000000',GradientType=0 )}r<\/style>\n<style type=\"text\/css\">.minimal-light .navigationbuttons,.minimal-light .esg-pagination,.minimal-light .esg-filters{text-align:center}.minimal-light .esg-filterbutton,.minimal-light .esg-navigationbutton,.minimal-light .esg-sortbutton,.minimal-light .esg-cartbutton a{color:#999; margin-right:5px; cursor:pointer; padding:0px 16px; border:1px solid #e5e5e5; line-height:38px; border-radius:5px; -moz-border-radius:5px; -webkit-border-radius:5px; font-size:12px; font-weight:700; font-family:\"Open Sans\",sans-serif; display:inline-block; background:#fff; margin-bottom:5px}.minimal-light .esg-navigationbutton *{color:#999}.minimal-light .esg-navigationbutton{padding:0px 16px}.minimal-light .esg-pagination-button:last-child{margin-right:0}.minimal-light .esg-left,.minimal-light .esg-right{padding:0px 11px}.minimal-light .esg-sortbutton-wrapper,.minimal-light .esg-cartbutton-wrapper{display:inline-block}.minimal-light .esg-sortbutton-order,.minimal-light .esg-cartbutton-order{display:inline-block;  vertical-align:top;  border:1px solid #e5e5e5;  width:40px;  line-height:38px;  border-radius:0px 5px 5px 0px;  -moz-border-radius:0px 5px 5px 0px;  -webkit-border-radius:0px 5px 5px 0px;  font-size:12px;  font-weight:700;  color:#999;  cursor:pointer;  background:#fff}.minimal-light .esg-cartbutton{color:#333; cursor:default !important}.minimal-light .esg-cartbutton .esgicon-basket{color:#333;   font-size:15px;   line-height:15px;   margin-right:10px}.minimal-light .esg-cartbutton-wrapper{cursor:default !important}.minimal-light .esg-sortbutton,.minimal-light .esg-cartbutton{display:inline-block; position:relative; cursor:pointer; margin-right:0px; border-right:none; border-radius:5px 0px 0px 5px; -moz-border-radius:5px 0px 0px 5px; -webkit-border-radius:5px 0px 0px 5px}.minimal-light .esg-navigationbutton:hover,.minimal-light .esg-filterbutton:hover,.minimal-light .esg-sortbutton:hover,.minimal-light .esg-sortbutton-order:hover,.minimal-light .esg-cartbutton a:hover,.minimal-light .esg-filterbutton.selected{background-color:#fff;   border-color:#bbb;   color:#333;   box-shadow:0px 3px 5px 0px rgba(0,0,0,0.13)}.minimal-light .esg-navigationbutton:hover *{color:#333}.minimal-light .esg-sortbutton-order.tp-desc:hover{border-color:#bbb; color:#333; box-shadow:0px -3px 5px 0px rgba(0,0,0,0.13) !important}.minimal-light .esg-filter-checked{padding:1px 3px;  color:#cbcbcb;  background:#cbcbcb;  margin-left:7px;  font-size:9px;  font-weight:300;  line-height:9px;  vertical-align:middle}.minimal-light .esg-filterbutton.selected .esg-filter-checked,.minimal-light .esg-filterbutton:hover .esg-filter-checked{padding:1px 3px 1px 3px;  color:#fff;  background:#000;  margin-left:7px;  font-size:9px;  font-weight:300;  line-height:9px;  vertical-align:middle}<\/style>\n<style type=\"text\/css\">.eg-howardtaft-v1-element-16{font-size:16px !important; line-height:22px !important; color:#ffffff !important; font-weight:400 !important; padding:17px 17px 17px 17px !important; border-radius:60px 60px 60px 60px !important; background:rgba(255,255,255,0) !important; z-index:2 !important; display:block; border-top-width:2px !important; border-right-width:2px !important; border-bottom-width:2px !important; border-left-width:2px !important; border-color:#ffffff !important; border-style:solid !important}<\/style>\n<style type=\"text\/css\">.eg-howardtaft-v1-element-16:hover{font-size:16px !important; line-height:22px !important; color:#000799 !important; font-weight:400 !important; border-radius:60px 60px 60px 60px !important; background:#ffffff !important; border-top-width:2px !important; border-right-width:2px !important; border-bottom-width:2px !important; border-left-width:2px !important; border-color:#ffffff !important; border-style:solid !important}<\/style>\n<style type=\"text\/css\">.eg-howardtaft-v1-element-16-a{display:inline-block !important; float:none !important; clear:none !important; margin:0px 10px 0px 0px !important; position:relative !important}<\/style>\n<style type=\"text\/css\">.eg-howardtaft-v1-container{background:rgba(0,0,22,0.32)}<\/style>\n<style type=\"text\/css\">.eg-howardtaft-v1-content{background:#000000; padding:0px 0px 0px 0px; border-width:0px 0px 0px 0px; border-radius:0px 0px 0px 0px; border-color:transparent; border-style:none; text-align:left}<\/style>\n<style type=\"text\/css\">.esg-grid .mainul li.eg-howardtaft-v1-wrapper{background:#000000; padding:0px 0px 0px 0px; border-width:0px 0px 0px 0px; border-radius:0px 0px 0px 0px; border-color:transparent; border-style:none}<\/style>\n<style type=\"text\/css\">.esg-grid .mainul li.eg-howardtaft-v1-wrapper .esg-media-poster{background-size:cover; background-position:center center; background-repeat:no-repeat}<\/style>\n<!-- THE ESSENTIAL GRID 3.0.12 CUSTOM -->\n\n<article class=\"myportfolio-container minimal-light source_type_custom\" id=\"esg-grid-5-1-wrap\">\n\n   <div id=\"esg-grid-5-1\" class=\"esg-grid\" style=\"background: transparent;padding: 0px 0px 0px 0px ; box-sizing:border-box; -moz-box-sizing:border-box; -webkit-box-sizing:border-box;\">\n<ul>\n<li id=\"eg-5-post-id-0_3409\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-0\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/inversion2-1000x750.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/inversion2-1000x750-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/inversion2-1000x750.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-1_6282\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-1\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/GOPR8279-1000x750.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/GOPR8279-1000x750-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/GOPR8279-1000x750.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-2_8342\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-2\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0064556-modifi\u00e9e-1000x750.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0064556-modifi\u00e9e-1000x750-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0064556-modifi\u00e9e-1000x750.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-3_9837\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-3\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0054530-600x800.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"800\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0054530-600x800-200x267.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0054530-600x800.jpg\" data-width=\"600\"  data-height=\"800\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-4_2381\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-4\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0048310-1000x750.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0048310-1000x750-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0048310-1000x750.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-5_8061\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-5\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0044516-1000x750.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0044516-1000x750-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0044516-1000x750.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-6_6895\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-6\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0034495-1000x750.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0034495-1000x750-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0034495-1000x750.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-7_3843\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-7\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/colt-virage-600x800.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"800\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/colt-virage-600x800-200x267.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/colt-virage-600x800.jpg\" data-width=\"600\"  data-height=\"800\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-8_2600\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-8\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/Au-d\u00e9co-\u00e0-La-ville-1000x750.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/Au-d\u00e9co-\u00e0-La-ville-1000x750-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/Au-d\u00e9co-\u00e0-La-ville-1000x750.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-9_6574\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-9\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/voile-au-gonflage-1000x750.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/voile-au-gonflage-1000x750-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/voile-au-gonflage-1000x750.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-10_8025\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-10\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/S\u00e9b-en-vol-600x800.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"800\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/S\u00e9b-en-vol-600x800-200x267.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/S\u00e9b-en-vol-600x800.jpg\" data-width=\"600\"  data-height=\"800\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-11_5202\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-11\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/Lbeau-temps-menace-600x800.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"800\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/Lbeau-temps-menace-600x800-200x267.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/Lbeau-temps-menace-600x800.jpg\" data-width=\"600\"  data-height=\"800\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-12_1936\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-12\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/PHOTO-2019-09-30-22-27-47-1000x750.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/PHOTO-2019-09-30-22-27-47-1000x750-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/PHOTO-2019-09-30-22-27-47-1000x750.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-13_1416\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-13\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/elevesradio.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/elevesradio-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/elevesradio.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-14_6070\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-14\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/elevescurn.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/elevescurn-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/elevescurn.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-15_3665\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-15\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/biplace_prep.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"800\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/biplace_prep-200x267.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/biplace_prep.jpg\" data-width=\"600\"  data-height=\"800\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-16_2266\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-16\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/GOPR8197.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/GOPR8197-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/GOPR8197.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-17_914\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-17\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/IMG_0309.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/IMG_0309-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/IMG_0309.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-18_6997\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-18\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/biplace_curneaux_4.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/biplace_curneaux_4-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/biplace_curneaux_4.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-19_8754\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-19\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/GOPR0416.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/GOPR0416-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/GOPR0416.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-20_1252\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-20\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0084302.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0084302-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0084302.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-21_9076\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-21\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0064296.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0064296-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0064296.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-22_8264\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-22\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/IMG_1108.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/IMG_1108-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/IMG_1108.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-23_6673\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-23\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0040067.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0040067-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/G0040067.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-24_9166\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-24\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/IMG_4313.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"600\" height=\"800\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/IMG_4313-200x267.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/IMG_4313.jpg\" data-width=\"600\"  data-height=\"800\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<li id=\"eg-5-post-id-25_4873\" data-skin=\"howardtaft-v1\" class=\"filterall eg-howardtaft-v1-wrapper eg-post-id-25\" data-date=\"\">\n    <div class=\"esg-media-cover-wrapper\">\n<div class=\"esg-entry-media\"><img src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/P1070626.jpg\" data-no-lazy=\"1\" alt=\"\" width=\"1000\" height=\"750\"><\/div>\n\n            <div class=\"esg-entry-cover\">\n\n                <div class=\"esg-overlay esg-transition eg-howardtaft-v1-container\" data-delay=\"0\" data-duration=\"default\" data-transition=\"esg-slide\"><\/div>\n\n\t\t\t\t<div class=\"esg-center eg-howardtaft-v1-element-16-a esg-transition\" data-delay=\"0.1\" data-duration=\"default\" data-transition=\"esg-slideright\"><a class=\"eg-howardtaft-v1-element-16 esgbox\" data-thumb=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/P1070626-200x150.jpg\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/P1070626.jpg\" data-width=\"1000\"  data-height=\"750\" ><i class=\"eg-icon-search\"><\/i><\/a><\/div>\n           <\/div>\n   <\/div>\n\n<\/li>\n<\/ul>\n<article class=\"esg-filters esg-singlefilters\" style=\"margin-top: 20px; text-align: center; \"><div class=\"esg-pagination  esg-fgc-5\" style=\"margin-left: 2.5px; margin-right: 2.5px;\"><\/div><\/article><div class=\"esg-clear-no-height\"><\/div>    <\/div>\n\n<\/article>\n<div class=\"clear\"><\/div>\n<script type=\"text\/javascript\">\nvar essapi_5_1;\nfunction esginit_5_1() {\njQuery(document).ready(function() {\n  essapi_5_1 = jQuery(\"#esg-grid-5-1\").tpessential({\n        gridID:5,\n        layout:\"even\",\n        forceFullWidth:\"off\",\n        lazyLoad:\"off\",\n        row:3,\n    apiName: \"essapi_5_1\",\n        loadMoreAjaxToken:\"d085230388\",\n        loadMoreAjaxUrl:\"https:\/\/www.dimension-3.ch\/18dim3\/wp-admin\/admin-ajax.php\",\n        loadMoreAjaxAction:\"Essential_Grid_Front_request_ajax\",\n        ajaxContentTarget:\"ess-grid-ajax-container-\",\n        ajaxScrollToOffset:\"0\",\n        ajaxCloseButton:\"off\",\n        ajaxContentSliding:\"on\",\n        ajaxScrollToOnLoad:\"on\",\n        ajaxCallbackArgument:\"off\",\n        ajaxNavButton:\"off\",\n        ajaxCloseType:\"type1\",\n        ajaxCloseInner:\"false\",\n        ajaxCloseStyle:\"light\",\n        ajaxClosePosition:\"tr\",\n        space:30,\n        pageAnimation:\"fade\",\n        videoPlaybackInGrid: \"on\",\n        videoPlaybackOnHover: \"off\",\n        videoInlineMute: \"on\",\n        videoInlineControls: \"off\",\n        keepLayersInline: \"off\",\n        startAnimation: \"none\",\n        startAnimationSpeed: 1000,\n        startAnimationDelay: 100,\n        startAnimationType: \"item\",\n        animationType: \"item\",\n        paginationScrollToTop:\"off\",\n        paginationAutoplay:\"off\",\n        spinner:\"spinner3\",\n        spinnerColor:\"#FFFFFF\",\n    minVisibleItems:3,\n        evenGridMasonrySkinPusher:\"on\",\n        lightBoxMode:\"filterall\",\n    lightboxHash:\"group\",\n    lightboxPostMinWid:\"75%\",\n    lightboxPostMaxWid:\"75%\",\n        lightboxSpinner:\"off\",\n        lightBoxFeaturedImg:\"off\",\n        lightBoxPostTitle:\"off\",\n        lightBoxPostTitleTag:\"h2\",\n    lightboxMargin : \"0|0|0|0\",\n    lbContentPadding : \"0|0|0|0\",\n    lbContentOverflow : \"auto\",\n        animSpeed:1000,\n        delayBasic:1,\n        mainhoverdelay:1,\n        filterType:\"single\",\n        showDropFilter:\"hover\",\n        filterGroupClass:\"esg-fgc-5\",\n        filterNoMatch:\"No Items for the Selected Filter\",\n        filterDeepLink:\"off\",\n        hideMarkups: \"on\",\n        inViewport: true,\n        viewportBuffer: 20,\n        youtubeNoCookie:\"false\",\n        convertFilterMobile:false,\n        paginationSwipe: \"off\",\n        paginationDragVer: \"on\",\n        pageSwipeThrottle: 30,\n        googleFonts:['Dosis:400,600','Dancing+Script:400,700','Roboto:400','Open+Sans:400,600,700','Raleway:100,200,300,400,500,600,700,800,900','Droid+Serif:400,700'],\n        aspectratio:\"4:3\",\n        hideBlankItemsAt: \"1\",\n        responsiveEntries: [\n            { width:1400,amount:5,mmheight:0},\n            { width:1170,amount:4,mmheight:0},\n            { width:1024,amount:4,mmheight:0},\n            { width:960,amount:3,mmheight:0},\n            { width:778,amount:3,mmheight:0},\n            { width:640,amount:3,mmheight:0},\n            { width:480,amount:1,mmheight:0}\n            ]\n  });\n\n  var arrows = true,\n        lightboxOptions = {\n    margin : [0,0,0,0],\n    buttons : [\"share\",\"thumbs\",\"close\"],\n    infobar : true,\n    loop : true,\n    slideShow : {\"autoStart\": false, \"speed\": 3000},\n    videoAutoPlay : true,\n    animationEffect : \"fade\",\n    animationDuration : 500,\n    beforeShow: function(a, c) {\n          if(!arrows) {\n              jQuery(\"body\").addClass(\"esgbox-hidearrows\");\n          }\n      var i = 0,\n        multiple = false;\n      a = a.slides;\n      for(var b in a) {\n        i++;\n        if(i > 1) {\n          multiple = true;\n          break;\n        }\n      }\n      if(!multiple) jQuery(\"body\").addClass(\"esgbox-single\");\n      if(c.type === \"image\") jQuery(\".esgbox-button--zoom\").show();\n    },\n    beforeLoad: function(a, b) {\n      jQuery(\"body\").removeClass(\"esg-four-by-three\");\n      if(b.opts.$orig.data(\"ratio\") === \"4:3\") jQuery(\"body\").addClass(\"esg-four-by-three\");\n    },\n    afterLoad: function() {jQuery(window).trigger(\"resize.esglb\");},\n    afterClose : function() {jQuery(\"body\").removeClass(\"esgbox-hidearrows esgbox-single\");},\n    transitionEffect : \"fade\",\n    transitionDuration : 366,\n    hash : \"group\",\n    arrows : true,\n    wheel : false,\n  };\n\n  jQuery(\"#esg-grid-5-1\").data(\"lightboxsettings\", lightboxOptions);\n\n\n});\n} \/\/ End of EsgInitScript\nvar once_5_1 = false;\nif (document.readyState === \"loading\") document.addEventListener('readystatechange',function() { if((document.readyState === \"interactive\" || document.readyState === \"complete\") && !once_5_1 ) { once_5_1 = true; esginit_5_1();}}); else {once_5_1 = true; esginit_5_1();}\n<\/script>\n\n                    <div class=\"clear\"><\/div>\r\n                <\/div>\r\n            <\/div>\r\n            <div class=\"clear\"><\/div>\r\n\n","protected":false},"excerpt":{"rendered":"Paragliding school Dimension 3 Become a pilot with the Dimension 3 paragliding school: Initiation, Progression, Performance. All you need to know about Dimension 3 internships Contact us","protected":false},"author":7,"featured_media":0,"parent":7012,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-FullWidth.php","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dimension 3 Gallery: Training of pilot students and paragliding internships<\/title>\n<meta name=\"description\" content=\"Dimension 3 Gallery: photos of the pilot students in introductory courses, solo patent license, refresher course, discovery day and tandem pedagogical course.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dimension 3 Gallery: Training of pilot students and paragliding internships\" \/>\n<meta property=\"og:description\" content=\"Dimension 3 Gallery: photos of the pilot students in introductory courses, solo patent license, refresher course, discovery day and tandem pedagogical course.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/\" \/>\n<meta property=\"og:site_name\" content=\"Dimension 3 | Vols biplace tandem et \u00e9cole de parapente \u00e0 Villars sur Ollon\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dimension3parapente\/\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-04T20:21:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/170320-website-Dimension-3.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1573\" \/>\n\t<meta property=\"og:image:height\" content=\"827\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dimension-3.ch\/18dim3\/#website\",\"url\":\"https:\/\/www.dimension-3.ch\/18dim3\/\",\"name\":\"Dimension 3 | Vols biplace tandem et \\u00e9cole de parapente \\u00e0 Villars sur Ollon\",\"description\":\"Tandem flights and paragliding school in Villars-sur-Ollon\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dimension-3.ch\/18dim3\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/#webpage\",\"url\":\"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/\",\"name\":\"Dimension 3 Gallery: Training of pilot students and paragliding internships\",\"isPartOf\":{\"@id\":\"https:\/\/www.dimension-3.ch\/18dim3\/#website\"},\"datePublished\":\"2016-11-06T19:01:21+00:00\",\"dateModified\":\"2019-03-04T20:21:47+00:00\",\"description\":\"Dimension 3 Gallery: photos of the pilot students in introductory courses, solo patent license, refresher course, discovery day and tandem pedagogical course.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dimension-3.ch\/18dim3\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gallery\",\"item\":\"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Dimension 3 Gallery: Training of pilot students and paragliding internships\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dimension 3 Gallery: Training of pilot students and paragliding internships","description":"Dimension 3 Gallery: photos of the pilot students in introductory courses, solo patent license, refresher course, discovery day and tandem pedagogical course.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/","og_locale":"en_US","og_type":"article","og_title":"Dimension 3 Gallery: Training of pilot students and paragliding internships","og_description":"Dimension 3 Gallery: photos of the pilot students in introductory courses, solo patent license, refresher course, discovery day and tandem pedagogical course.","og_url":"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/","og_site_name":"Dimension 3 | Vols biplace tandem et \u00e9cole de parapente \u00e0 Villars sur Ollon","article_publisher":"https:\/\/www.facebook.com\/dimension3parapente\/","article_modified_time":"2019-03-04T20:21:47+00:00","og_image":[{"width":1573,"height":827,"url":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/170320-website-Dimension-3.png","type":"image\/png"}],"twitter_card":"summary","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.dimension-3.ch\/18dim3\/#website","url":"https:\/\/www.dimension-3.ch\/18dim3\/","name":"Dimension 3 | Vols biplace tandem et \u00e9cole de parapente \u00e0 Villars sur Ollon","description":"Tandem flights and paragliding school in Villars-sur-Ollon","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dimension-3.ch\/18dim3\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/#webpage","url":"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/","name":"Dimension 3 Gallery: Training of pilot students and paragliding internships","isPartOf":{"@id":"https:\/\/www.dimension-3.ch\/18dim3\/#website"},"datePublished":"2016-11-06T19:01:21+00:00","dateModified":"2019-03-04T20:21:47+00:00","description":"Dimension 3 Gallery: photos of the pilot students in introductory courses, solo patent license, refresher course, discovery day and tandem pedagogical course.","breadcrumb":{"@id":"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/dimension-3-gallery-training-of-pilot-students-and-paragliding-internships\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dimension-3.ch\/18dim3\/en\/"},{"@type":"ListItem","position":2,"name":"Gallery","item":"https:\/\/www.dimension-3.ch\/18dim3\/en\/gallery\/"},{"@type":"ListItem","position":3,"name":"Dimension 3 Gallery: Training of pilot students and paragliding internships"}]}]}},"_links":{"self":[{"href":"https:\/\/www.dimension-3.ch\/18dim3\/en\/wp-json\/wp\/v2\/pages\/6517"}],"collection":[{"href":"https:\/\/www.dimension-3.ch\/18dim3\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.dimension-3.ch\/18dim3\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.dimension-3.ch\/18dim3\/en\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dimension-3.ch\/18dim3\/en\/wp-json\/wp\/v2\/comments?post=6517"}],"version-history":[{"count":0,"href":"https:\/\/www.dimension-3.ch\/18dim3\/en\/wp-json\/wp\/v2\/pages\/6517\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.dimension-3.ch\/18dim3\/en\/wp-json\/wp\/v2\/pages\/7012"}],"wp:attachment":[{"href":"https:\/\/www.dimension-3.ch\/18dim3\/en\/wp-json\/wp\/v2\/media?parent=6517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}