{"id":4301,"date":"2015-06-13T15:13:54","date_gmt":"2015-06-13T19:13:54","guid":{"rendered":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png"},"modified":"2015-06-13T15:14:06","modified_gmt":"2015-06-13T19:14:06","slug":"u-design-options-page-sections-collapsed","status":"inherit","type":"attachment","link":"https:\/\/www.dimension-3.ch\/18dim3\/u-design-options-page-sections-collapsed\/","title":{"rendered":"u-design-options-page-sections-collapsed"},"author":4,"comment_status":"open","ping_status":"closed","template":"","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>u-design-options-page-sections-collapsed<\/title>\n<meta name=\"description\" content=\"All Options (Collapsed View)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"u-design-options-page-sections-collapsed\" \/>\n<meta property=\"og:description\" content=\"All Options (Collapsed View)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png\" \/>\n<meta property=\"og:site_name\" content=\"Dimension 3 | Vols biplace tandem et \u00e9cole de parapente \u00e0 Villars sur Ollon\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dimension3parapente\/\" \/>\n<meta property=\"article:modified_time\" content=\"2015-06-13T19:14:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1242\" \/>\n\t<meta property=\"og:image:height\" content=\"1013\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dimension-3.ch\/18dim3\/#website\",\"url\":\"https:\/\/www.dimension-3.ch\/18dim3\/\",\"name\":\"Dimension 3 | Vols biplace tandem et \\u00e9cole de parapente \\u00e0 Villars sur Ollon\",\"description\":\"Vols tandem et \\u00e9cole de parapente \\u00e0 Villars sur Ollon\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dimension-3.ch\/18dim3\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png#webpage\",\"url\":\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png\",\"name\":\"u-design-options-page-sections-collapsed\",\"isPartOf\":{\"@id\":\"https:\/\/www.dimension-3.ch\/18dim3\/#website\"},\"datePublished\":\"2015-06-13T19:13:54+00:00\",\"dateModified\":\"2015-06-13T19:14:06+00:00\",\"description\":\"All Options (Collapsed View)\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dimension-3.ch\/18dim3\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"u-design-options-page-sections-collapsed\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"u-design-options-page-sections-collapsed","description":"All Options (Collapsed View)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png","og_locale":"fr_FR","og_type":"article","og_title":"u-design-options-page-sections-collapsed","og_description":"All Options (Collapsed View)","og_url":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png","og_site_name":"Dimension 3 | Vols biplace tandem et \u00e9cole de parapente \u00e0 Villars sur Ollon","article_publisher":"https:\/\/www.facebook.com\/dimension3parapente\/","article_modified_time":"2015-06-13T19:14:06+00:00","og_image":[{"width":1242,"height":1013,"url":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png","type":"image\/png"}],"twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.dimension-3.ch\/18dim3\/#website","url":"https:\/\/www.dimension-3.ch\/18dim3\/","name":"Dimension 3 | Vols biplace tandem et \u00e9cole de parapente \u00e0 Villars sur Ollon","description":"Vols tandem et \u00e9cole de parapente \u00e0 Villars sur Ollon","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dimension-3.ch\/18dim3\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png#webpage","url":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png","name":"u-design-options-page-sections-collapsed","isPartOf":{"@id":"https:\/\/www.dimension-3.ch\/18dim3\/#website"},"datePublished":"2015-06-13T19:13:54+00:00","dateModified":"2015-06-13T19:14:06+00:00","description":"All Options (Collapsed View)","breadcrumb":{"@id":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dimension-3.ch\/18dim3\/"},{"@type":"ListItem","position":2,"name":"u-design-options-page-sections-collapsed"}]}]}},"description":{"rendered":"<p class=\"attachment\"><a rel='wp-prettyPhoto' href='https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png' rel=\"wp-prettyPhoto[4301]\"><img width=\"300\" height=\"245\" src=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed-300x245.png\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed-300x245.png 300w, https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed-1024x835.png 1024w, https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png 1242w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>All Options (Collapsed View)<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1242,"height":1013,"file":"2011\/01\/u-design-options-page-sections-collapsed.png","sizes":{"thumbnail":{"file":"u-design-options-page-sections-collapsed-150x150.png","width":150,"height":150,"mime_type":"image\/png","source_url":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed-150x150.png"},"medium":{"file":"u-design-options-page-sections-collapsed-300x245.png","width":300,"height":245,"mime_type":"image\/png","source_url":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed-300x245.png"},"large":{"file":"u-design-options-page-sections-collapsed-1024x835.png","width":1024,"height":835,"mime_type":"image\/png","source_url":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed-1024x835.png"},"full":{"file":"u-design-options-page-sections-collapsed.png","width":1242,"height":1013,"mime_type":"image\/png","source_url":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":"","orientation":0,"resized_images":["180x120_c"]}},"post":null,"source_url":"https:\/\/www.dimension-3.ch\/18dim3\/wp-content\/uploads\/2011\/01\/u-design-options-page-sections-collapsed.png","_links":{"self":[{"href":"https:\/\/www.dimension-3.ch\/18dim3\/wp-json\/wp\/v2\/media\/4301"}],"collection":[{"href":"https:\/\/www.dimension-3.ch\/18dim3\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.dimension-3.ch\/18dim3\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.dimension-3.ch\/18dim3\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.dimension-3.ch\/18dim3\/wp-json\/wp\/v2\/comments?post=4301"}]}}